{"id":37239,"date":"2018-04-08T17:42:43","date_gmt":"2018-04-08T10:42:43","guid":{"rendered":"http:\/\/www.benewsonline.com\/home\/?p=37239"},"modified":"2018-04-08T10:56:36","modified_gmt":"2018-04-08T03:56:36","slug":"hotels-com-%e0%b8%a1%e0%b8%ad%e0%b8%9a%e0%b8%aa%e0%b9%88%e0%b8%a7%e0%b8%99%e0%b8%a5%e0%b8%94%e0%b8%9e%e0%b8%b4%e0%b9%80%e0%b8%a8%e0%b8%a9%e0%b8%aa%e0%b8%b9%e0%b8%87%e0%b8%aa%e0%b8%b8%e0%b8%94-40","status":"publish","type":"post","link":"https:\/\/www.benewsonline.com\/home\/2018\/04\/hotels-com-%e0%b8%a1%e0%b8%ad%e0%b8%9a%e0%b8%aa%e0%b9%88%e0%b8%a7%e0%b8%99%e0%b8%a5%e0%b8%94%e0%b8%9e%e0%b8%b4%e0%b9%80%e0%b8%a8%e0%b8%a9%e0%b8%aa%e0%b8%b9%e0%b8%87%e0%b8%aa%e0%b8%b8%e0%b8%94-40\/","title":{"rendered":"Hotels.com \u0e21\u0e2d\u0e1a\u0e2a\u0e48\u0e27\u0e19\u0e25\u0e14\u0e1e\u0e34\u0e40\u0e28\u0e29\u0e2a\u0e39\u0e07\u0e2a\u0e38\u0e14 40% \u0e15\u0e49\u0e2d\u0e19\u0e23\u0e31\u0e1a\u0e2a\u0e07\u0e01\u0e23\u0e32\u0e19\u0e15\u0e4c"},"content":{"rendered":"<p>\u0e40\u0e14\u0e37\u0e2d\u0e19\u0e41\u0e2b\u0e48\u0e07\u0e04\u0e27\u0e32\u0e21\u0e0a\u0e38\u0e48\u0e21\u0e09\u0e48\u0e33\u0e17\u0e35\u0e48\u0e2a\u0e38\u0e14\u0e43\u0e19\u0e40\u0e21\u0e37\u0e2d\u0e07\u0e44\u0e17\u0e22\u0e40\u0e27\u0e35\u0e22\u0e19\u0e21\u0e32\u0e16\u0e36\u0e07\u0e2d\u0e35\u0e01\u0e23\u0e2d\u0e1a\u0e2b\u0e19\u0e36\u0e48\u0e07\u0e41\u0e25\u0e49\u0e27\u0e01\u0e31\u0e1a\u0e40\u0e17\u0e28\u0e01\u0e32\u0e25\u0e2a\u0e07\u0e01\u0e23\u0e32\u0e19\u0e15\u0e4c\u0e1b\u0e23\u0e30\u0e08\u0e33\u0e1b\u0e35 2561 <a href=\"https:\/\/th.hotels.com\/?rffrid=seo.hcom.PR.TH.me.Songkran.042018\">Hotels.com\u2122<\/a> \u0e44\u0e21\u0e48\u0e1e\u0e25\u0e32\u0e14\u0e17\u0e35\u0e48\u0e08\u0e30\u0e2a\u0e48\u0e07\u0e14\u0e35\u0e25\u0e1e\u0e34\u0e40\u0e28\u0e29\u0e2a\u0e38\u0e14\u0e04\u0e38\u0e49\u0e21\u0e15\u0e49\u0e2d\u0e19\u0e23\u0e31\u0e1a\u0e1b\u0e34\u0e14\u0e40\u0e17\u0e2d\u0e21\u0e41\u0e25\u0e30\u0e27\u0e31\u0e19\u0e2b\u0e22\u0e38\u0e14\u0e22\u0e32\u0e27\u0e43\u0e19\u0e0a\u0e48\u0e27\u0e07\u0e2a\u0e07\u0e01\u0e23\u0e32\u0e19\u0e15\u0e4c\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e08\u0e2d\u0e07\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e17\u0e35\u0e48\u0e44\u0e2b\u0e19\u0e01\u0e47\u0e44\u0e14\u0e49\u0e17\u0e31\u0e48\u0e27\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22\u0e41\u0e25\u0e30\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e25\u0e14\u0e2a\u0e39\u0e07\u0e2a\u0e38\u0e14 40% \u0e40\u0e15\u0e23\u0e35\u0e22\u0e21\u0e15\u0e31\u0e27\u0e44\u0e1b\u0e04\u0e25\u0e32\u0e22\u0e23\u0e49\u0e2d\u0e19\u0e41\u0e25\u0e30\u0e40\u0e25\u0e48\u0e19\u0e19\u0e49\u0e33\u0e43\u0e19\u0e0a\u0e48\u0e27\u0e07\u0e27\u0e31\u0e19\u0e2b\u0e22\u0e38\u0e14\u0e01\u0e31\u0e1a\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e19 \u0e46 \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e42\u0e1b\u0e23\u0e42\u0e21\u0e0a\u0e31\u0e48\u0e19\u0e08\u0e2d\u0e07\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2a\u0e38\u0e14\u0e04\u0e38\u0e49\u0e21\u0e44\u0e14\u0e49\u0e41\u0e25\u0e49\u0e27\u0e27\u0e31\u0e19\u0e19\u0e35\u0e49<\/p>\n<p>\u0e08\u0e2d\u0e07\u0e44\u0e14\u0e49\u0e41\u0e25\u0e49\u0e27<strong>\u0e15\u0e31\u0e49\u0e07\u0e41\u0e15\u0e48\u0e27\u0e31\u0e19\u0e19\u0e35\u0e49\u0e08\u0e19\u0e16\u0e36\u0e07\u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 30 \u0e40\u0e21\u0e29\u0e32\u0e22\u0e19 2561<\/strong> \u0e1a\u0e19 <a href=\"https:\/\/th.hotels.com\/?rffrid=seo.hcom.PR.TH.me.Songkran.042018\">\u0e40\u0e27\u0e47\u0e1a\u0e44\u0e0b\u0e15\u0e4c Hotels.com<\/a> \u0e41\u0e25\u0e30 <a href=\"https:\/\/th.hotels.com\/page\/app\/?rffrid=seo.hcom.PR.TH.me.Songkran.042018\">\u0e41\u0e2d\u0e1e\u0e1e\u0e25\u0e34\u0e40\u0e04\u0e0a\u0e31\u0e48\u0e19 Hotels.com<\/a> \u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e40\u0e14\u0e34\u0e19\u0e17\u0e32\u0e07\u0e15\u0e31\u0e49\u0e07\u0e41\u0e15\u0e48\u0e27\u0e31\u0e19\u0e19\u0e35\u0e49\u0e16\u0e36\u0e07 27 \u0e1e\u0e24\u0e29\u0e20\u0e32\u0e04\u0e21 2561 \u0e40\u0e25\u0e37\u0e2d\u0e01\u0e08\u0e2d\u0e07\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e17\u0e35\u0e48\u0e43\u0e0a\u0e48 \u0e41\u0e25\u0e30\u0e2a\u0e19\u0e38\u0e01\u0e44\u0e1b\u0e43\u0e2b\u0e49\u0e2a\u0e38\u0e14\u0e01\u0e31\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e40\u0e09\u0e25\u0e34\u0e21\u0e09\u0e25\u0e2d\u0e07\u0e40\u0e17\u0e28\u0e01\u0e32\u0e25\u0e2a\u0e07\u0e01\u0e23\u0e32\u0e19\u0e15\u0e4c\u0e17\u0e31\u0e48\u0e27\u0e17\u0e31\u0e49\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22 <a href=\"https:\/\/th.hotels.com\/?rffrid=seo.hcom.PR.TH.me.Songkran.042018\">Hotels.com<\/a> \u0e21\u0e35\u0e15\u0e31\u0e27\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e41\u0e25\u0e30\u0e2d\u0e35\u0e40\u0e27\u0e49\u0e19\u0e17\u0e4c\u0e17\u0e35\u0e48\u0e19\u0e48\u0e32\u0e2a\u0e19\u0e43\u0e08\u0e15\u0e48\u0e32\u0e07 \u0e46 \u0e14\u0e31\u0e07\u0e15\u0e48\u0e2d\u0e44\u0e1b\u0e19\u0e35\u0e49<\/p>\n<p>\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e17\u0e48\u0e32\u0e19\u0e17\u0e35\u0e48\u0e2d\u0e22\u0e39\u0e48\u0e43\u0e19\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e2f \u0e41\u0e25\u0e30\u0e44\u0e21\u0e48\u0e44\u0e14\u0e49\u0e40\u0e14\u0e34\u0e19\u0e17\u0e32\u0e07\u0e2d\u0e2d\u0e01\u0e44\u0e1b\u0e15\u0e48\u0e32\u0e07\u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14 \u0e2b\u0e23\u0e37\u0e2d\u0e17\u0e48\u0e32\u0e19\u0e43\u0e14\u0e17\u0e35\u0e48\u0e40\u0e14\u0e34\u0e19\u0e17\u0e32\u0e07\u0e21\u0e32\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e2a\u0e19\u0e38\u0e01\u0e44\u0e1b\u0e01\u0e31\u0e1a\u0e40\u0e17\u0e28\u0e01\u0e32\u0e25\u0e14\u0e19\u0e15\u0e23\u0e35\u0e2a\u0e38\u0e14\u0e22\u0e34\u0e48\u0e07\u0e43\u0e2b\u0e0d\u0e48\u0e2d\u0e22\u0e48\u0e32\u0e07 <a href=\"https:\/\/www.s2ofestival.com\/\">S2O Songkran Music Festival 2018<\/a> \u0e04\u0e2d\u0e40\u0e1e\u0e25\u0e07\u0e41\u0e19\u0e27 EDM \u0e44\u0e21\u0e48\u0e04\u0e27\u0e23\u0e1e\u0e25\u0e32\u0e14 \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e40\u0e25\u0e48\u0e19\u0e19\u0e49\u0e33\u0e23\u0e39\u0e1b\u0e41\u0e1a\u0e1a\u0e43\u0e2b\u0e21\u0e48 360 \u0e2d\u0e07\u0e28\u0e32\u0e43\u0e2b\u0e49\u0e1f\u0e34\u0e19\u0e15\u0e25\u0e2d\u0e14\u0e17\u0e31\u0e49\u0e07\u0e2a\u0e32\u0e21\u0e27\u0e31\u0e19\u0e15\u0e34\u0e14 \u0e2b\u0e25\u0e31\u0e07\u0e08\u0e32\u0e01\u0e1b\u0e32\u0e23\u0e4c\u0e15\u0e35\u0e49\u0e41\u0e25\u0e30\u0e40\u0e25\u0e48\u0e19\u0e19\u0e49\u0e33\u0e21\u0e32\u0e17\u0e31\u0e49\u0e07\u0e27\u0e31\u0e19\u0e41\u0e25\u0e49\u0e27\u0e25\u0e2d\u0e07\u0e21\u0e2d\u0e07\u0e2b\u0e32\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e43\u0e01\u0e25\u0e49\u0e01\u0e31\u0e1a Live Park \u0e1e\u0e23\u0e30\u0e23\u0e32\u0e21 9 \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e08\u0e31\u0e14\u0e07\u0e32\u0e19 \u0e2d\u0e32\u0e17\u0e34 <a href=\"https:\/\/th.hotels.com\/ho637631776\/?rffrid=seo.hcom.PR.TH.me.Songkran.042018\">Zazz Urban Bangkok<\/a> \u0e40\u0e1e\u0e35\u0e22\u0e07 5 \u0e19\u0e32\u0e17\u0e35\u0e42\u0e14\u0e22\u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c \u0e2b\u0e23\u0e37\u0e2d <a href=\"https:\/\/th.hotels.com\/ho590672\/?rffrid=seo.hcom.PR.TH.me.Songkran.042018\">\u0e42\u0e23\u0e07\u0e41\u0e23\u0e21\u0e41\u0e25\u0e07\u0e04\u0e32\u0e2a\u0e40\u0e15\u0e2d\u0e23\u0e4c<\/a> \u0e17\u0e35\u0e48\u0e40\u0e1e\u0e34\u0e48\u0e07\u0e40\u0e1b\u0e34\u0e14\u0e43\u0e2b\u0e21\u0e48\u0e01\u0e47\u0e40\u0e1b\u0e47\u0e19\u0e2d\u0e35\u0e01\u0e2b\u0e19\u0e36\u0e48\u0e07\u0e15\u0e31\u0e27\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e17\u0e35\u0e48\u0e19\u0e48\u0e32\u0e2a\u0e19\u0e43\u0e08\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e01\u0e1c\u0e48\u0e2d\u0e19\u0e2b\u0e25\u0e31\u0e07\u0e08\u0e32\u0e01\u0e2a\u0e19\u0e38\u0e01\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e40\u0e25\u0e48\u0e19\u0e19\u0e49\u0e33 \u0e0b\u0e36\u0e48\u0e07\u0e2d\u0e22\u0e39\u0e48\u0e43\u0e01\u0e25\u0e49\u0e01\u0e31\u0e1a\u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e08\u0e31\u0e14\u0e07\u0e32\u0e19\u0e40\u0e0a\u0e48\u0e19\u0e01\u0e31\u0e19<\/p>\n<p><a href=\"http:\/\/www.benewsonline.com\/wp-content\/uploads\/2018\/04\/temple.jpg\"><img fetchpriority=\"high\" decoding=\"async\" class=\"size-large wp-image-37241\" src=\"http:\/\/www.benewsonline.com\/wp-content\/uploads\/2018\/04\/temple-1024x680.jpg\" alt=\"\" width=\"800\" height=\"531\" srcset=\"https:\/\/www.benewsonline.com\/wp-content\/uploads\/2018\/04\/temple-1024x680.jpg 1024w, https:\/\/www.benewsonline.com\/wp-content\/uploads\/2018\/04\/temple-300x199.jpg 300w, https:\/\/www.benewsonline.com\/wp-content\/uploads\/2018\/04\/temple-768x510.jpg 768w, https:\/\/www.benewsonline.com\/wp-content\/uploads\/2018\/04\/temple.jpg 1158w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/a><\/p>\n<p>\u0e2b\u0e32\u0e01\u0e2d\u0e22\u0e32\u0e01\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e1a\u0e23\u0e23\u0e22\u0e32\u0e01\u0e32\u0e28\u0e44\u0e1b\u0e40\u0e25\u0e48\u0e19\u0e2a\u0e07\u0e01\u0e23\u0e32\u0e19\u0e15\u0e4c\u0e41\u0e1a\u0e1a non stop \u0e22\u0e32\u0e27 \u0e46 \u0e44\u0e1b\u0e16\u0e36\u0e07\u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 19 \u0e40\u0e21\u0e29\u0e32\u0e22\u0e19 \u0e1e\u0e31\u0e17\u0e22\u0e32\u0e19\u0e48\u0e32\u0e08\u0e30\u0e40\u0e1b\u0e47\u0e19\u0e15\u0e31\u0e27\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e17\u0e35\u0e48\u0e14\u0e35\u0e17\u0e35\u0e48\u0e2a\u0e38\u0e14\u0e01\u0e31\u0e1a\u0e40\u0e17\u0e28\u0e01\u0e32\u0e25\u0e07\u0e32\u0e19\u0e27\u0e31\u0e19\u0e44\u0e2b\u0e19\u0e1e\u0e31\u0e17\u0e22\u0e32\u0e15\u0e31\u0e49\u0e07\u0e41\u0e15\u0e48\u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 13-19 \u0e40\u0e21\u0e29\u0e32\u0e22\u0e19 2561 \u0e0b\u0e36\u0e48\u0e07\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e04\u0e27\u0e32\u0e21\u0e19\u0e34\u0e22\u0e21\u0e43\u0e19\u0e01\u0e25\u0e38\u0e48\u0e21\u0e19\u0e31\u0e01\u0e17\u0e48\u0e2d\u0e07\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27\u0e0a\u0e32\u0e27\u0e44\u0e17\u0e22\u0e41\u0e25\u0e30\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e2b\u0e23\u0e37\u0e2d\u0e17\u0e48\u0e32\u0e19\u0e43\u0e14\u0e17\u0e35\u0e48\u0e2d\u0e22\u0e32\u0e01\u0e1e\u0e31\u0e01\u0e08\u0e32\u0e01\u0e01\u0e32\u0e23\u0e2a\u0e32\u0e14\u0e19\u0e49\u0e33\u0e01\u0e47\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e40\u0e02\u0e49\u0e32\u0e23\u0e48\u0e27\u0e21\u0e1b\u0e23\u0e30\u0e40\u0e1e\u0e13\u0e35\u0e01\u0e48\u0e2d\u0e1e\u0e23\u0e30\u0e17\u0e23\u0e32\u0e22\u0e41\u0e1a\u0e1a\u0e14\u0e31\u0e49\u0e07\u0e40\u0e14\u0e34\u0e21\u0e17\u0e35\u0e48\u0e1a\u0e32\u0e07\u0e41\u0e2a\u0e19\u0e44\u0e14\u0e49\u0e40\u0e0a\u0e48\u0e19\u0e01\u0e31\u0e19 \u0e41\u0e25\u0e30\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e1a\u0e23\u0e34\u0e40\u0e27\u0e13\u0e43\u0e01\u0e25\u0e49\u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e08\u0e31\u0e14\u0e07\u0e32\u0e19\u0e17\u0e35\u0e48\u0e19\u0e48\u0e32\u0e2a\u0e19\u0e43\u0e08\u0e44\u0e14\u0e49\u0e41\u0e01\u0e48 <a href=\"https:\/\/th.hotels.com\/ho450169\/?rffrid=seo.hcom.PR.TH.me.Songkran.042018\">\u0e42\u0e23\u0e07\u0e41\u0e23\u0e21\u0e17\u0e23\u0e2d\u0e1b\u0e34\u0e04\u0e32\u0e19\u0e32<\/a> \u0e42\u0e23\u0e07\u0e41\u0e23\u0e21\u0e23\u0e34\u0e21\u0e2b\u0e32\u0e14\u0e1e\u0e31\u0e17\u0e22\u0e32, <a href=\"https:\/\/th.hotels.com\/ho478149\/?rffrid=seo.hcom.PR.TH.me.Songkran.042018\">\u0e17\u0e27\u0e35\u0e15 \u0e17\u0e27\u0e35\u0e15 \u0e40\u0e19\u0e2a\u0e17\u0e4c \u0e1e\u0e31\u0e17\u0e22\u0e32<\/a> \u0e42\u0e23\u0e07\u0e41\u0e23\u0e21\u0e2a\u0e44\u0e15\u0e25\u0e4c\u0e2d\u0e32\u0e23\u0e4c\u0e15\u0e40\u0e14\u0e42\u0e04\u0e23\u0e34\u0e21\u0e17\u0e30\u0e40\u0e25 \u0e41\u0e25\u0e30 <a href=\"https:\/\/th.hotels.com\/ho678084\/?rffrid=seo.hcom.PR.TH.me.Songkran.042018\">\u0e42\u0e04\u0e42\u0e04\u0e48 \u0e1a\u0e35\u0e0a \u0e23\u0e35\u0e2a\u0e2d\u0e23\u0e4c\u0e17 \u0e1a\u0e32\u0e07\u0e41\u0e2a\u0e19<\/a> \u0e42\u0e23\u0e07\u0e41\u0e23\u0e21\u0e23\u0e34\u0e21\u0e0a\u0e32\u0e22\u0e2b\u0e32\u0e14\u0e1a\u0e32\u0e07\u0e41\u0e2a\u0e19<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u0e40\u0e14\u0e37\u0e2d\u0e19\u0e41\u0e2b\u0e48\u0e07\u0e04\u0e27\u0e32\u0e21\u0e0a\u0e38\u0e48\u0e21\u0e09\u0e48\u0e33\u0e17\u0e35\u0e48\u0e2a\u0e38\u0e14\u0e43\u0e19\u0e40\u0e21\u0e37\u0e2d\u0e07\u0e44\u0e17\u0e22\u0e40\u0e27\u0e35\u0e22\u0e19\u0e21\u0e32\u0e16\u0e36\u0e07\u0e2d\u0e35\u0e01\u0e23\u0e2d\u0e1a\u0e2b\u0e19\u0e36\u0e48\u0e07\u0e41\u0e25\u0e49\u0e27\u0e01\u0e31\u0e1a\u0e40\u0e17\u0e28\u0e01\u0e32\u0e25\u0e2a\u0e07\u0e01\u0e23\u0e32\u0e19\u0e15\u0e4c\u0e1b\u0e23\u0e30\u0e08\u0e33\u0e1b\u0e35 2561 Hotels.com\u2122 \u0e44\u0e21\u0e48\u0e1e\u0e25\u0e32\u0e14\u0e17\u0e35\u0e48\u0e08\u0e30\u0e2a\u0e48\u0e07\u0e14\u0e35\u0e25\u0e1e\u0e34\u0e40\u0e28\u0e29\u0e2a\u0e38\u0e14\u0e04\u0e38\u0e49\u0e21\u0e15\u0e49\u0e2d\u0e19\u0e23\u0e31\u0e1a\u0e1b\u0e34\u0e14\u0e40\u0e17\u0e2d\u0e21\u0e41\u0e25\u0e30\u0e27\u0e31\u0e19\u0e2b\u0e22\u0e38\u0e14\u0e22\u0e32\u0e27\u0e43\u0e19\u0e0a\u0e48\u0e27\u0e07\u0e2a\u0e07\u0e01\u0e23\u0e32\u0e19\u0e15\u0e4c\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e08\u0e2d\u0e07\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e17\u0e35\u0e48\u0e44\u0e2b\u0e19\u0e01\u0e47\u0e44\u0e14\u0e49\u0e17\u0e31\u0e48\u0e27\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22\u0e41\u0e25\u0e30\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e25\u0e14\u0e2a\u0e39\u0e07\u0e2a\u0e38\u0e14 40% \u0e40\u0e15\u0e23\u0e35\u0e22\u0e21\u0e15\u0e31\u0e27\u0e44\u0e1b\u0e04\u0e25\u0e32\u0e22\u0e23\u0e49\u0e2d\u0e19\u0e41\u0e25\u0e30\u0e40\u0e25\u0e48\u0e19\u0e19\u0e49\u0e33\u0e43\u0e19\u0e0a\u0e48\u0e27\u0e07\u0e27\u0e31\u0e19\u0e2b\u0e22\u0e38\u0e14\u0e01\u0e31\u0e1a\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e19 \u0e46 \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e42\u0e1b\u0e23\u0e42\u0e21\u0e0a\u0e31\u0e48\u0e19\u0e08\u0e2d\u0e07\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2a\u0e38\u0e14\u0e04\u0e38\u0e49\u0e21\u0e44\u0e14\u0e49\u0e41\u0e25\u0e49\u0e27\u0e27\u0e31\u0e19\u0e19\u0e35\u0e49 \u0e08\u0e2d\u0e07\u0e44\u0e14\u0e49\u0e41\u0e25\u0e49\u0e27\u0e15\u0e31\u0e49\u0e07\u0e41\u0e15\u0e48\u0e27\u0e31\u0e19\u0e19\u0e35\u0e49\u0e08\u0e19\u0e16\u0e36\u0e07\u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 30 \u0e40\u0e21\u0e29\u0e32\u0e22\u0e19 2561 \u0e1a\u0e19 \u0e40\u0e27\u0e47\u0e1a\u0e44\u0e0b\u0e15\u0e4c Hotels.com \u0e41\u0e25\u0e30 \u0e41\u0e2d\u0e1e\u0e1e\u0e25\u0e34\u0e40\u0e04\u0e0a\u0e31\u0e48\u0e19 Hotels.com \u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e40\u0e14\u0e34\u0e19\u0e17\u0e32\u0e07\u0e15\u0e31\u0e49\u0e07\u0e41\u0e15\u0e48\u0e27\u0e31\u0e19\u0e19\u0e35\u0e49\u0e16\u0e36\u0e07 27<\/p>\n","protected":false},"author":3,"featured_media":37240,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","footnotes":""},"categories":[7],"tags":[],"class_list":["post-37239","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-travel"],"_links":{"self":[{"href":"https:\/\/www.benewsonline.com\/home\/wp-json\/wp\/v2\/posts\/37239","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.benewsonline.com\/home\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.benewsonline.com\/home\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.benewsonline.com\/home\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.benewsonline.com\/home\/wp-json\/wp\/v2\/comments?post=37239"}],"version-history":[{"count":1,"href":"https:\/\/www.benewsonline.com\/home\/wp-json\/wp\/v2\/posts\/37239\/revisions"}],"predecessor-version":[{"id":37242,"href":"https:\/\/www.benewsonline.com\/home\/wp-json\/wp\/v2\/posts\/37239\/revisions\/37242"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.benewsonline.com\/home\/wp-json\/wp\/v2\/media\/37240"}],"wp:attachment":[{"href":"https:\/\/www.benewsonline.com\/home\/wp-json\/wp\/v2\/media?parent=37239"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.benewsonline.com\/home\/wp-json\/wp\/v2\/categories?post=37239"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.benewsonline.com\/home\/wp-json\/wp\/v2\/tags?post=37239"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}