{"id":107774,"date":"2023-04-05T20:26:31","date_gmt":"2023-04-05T13:26:31","guid":{"rendered":"https:\/\/www.benewsonline.com\/home\/?p=107774"},"modified":"2023-04-05T20:26:31","modified_gmt":"2023-04-05T13:26:31","slug":"%e0%b8%a3%e0%b8%96%e0%b8%88%e0%b8%b1%e0%b8%81%e0%b8%a3%e0%b8%a2%e0%b8%b2%e0%b8%99%e0%b8%a2%e0%b8%99%e0%b8%95%e0%b9%8c%e0%b8%ae%e0%b8%ad%e0%b8%99%e0%b8%94%e0%b9%89%e0%b8%b2-%e0%b8%84%e0%b8%a7-2","status":"publish","type":"post","link":"https:\/\/www.benewsonline.com\/home\/2023\/04\/%e0%b8%a3%e0%b8%96%e0%b8%88%e0%b8%b1%e0%b8%81%e0%b8%a3%e0%b8%a2%e0%b8%b2%e0%b8%99%e0%b8%a2%e0%b8%99%e0%b8%95%e0%b9%8c%e0%b8%ae%e0%b8%ad%e0%b8%99%e0%b8%94%e0%b9%89%e0%b8%b2-%e0%b8%84%e0%b8%a7-2\/","title":{"rendered":"\u0e23\u0e16\u0e08\u0e31\u0e01\u0e23\u0e22\u0e32\u0e19\u0e22\u0e19\u0e15\u0e4c\u0e2e\u0e2d\u0e19\u0e14\u0e49\u0e32 \u0e04\u0e27\u0e49\u0e32\u0e23\u0e32\u0e07\u0e27\u0e31\u0e25\u0e43\u0e2b\u0e0d\u0e48 Thailand\u2019s Most Admired Brand 2023 \u0e08\u0e32\u0e01 BrandAge"},"content":{"rendered":"<p>\u0e23\u0e16\u0e08\u0e31\u0e01\u0e23\u0e22\u0e32\u0e19\u0e22\u0e19\u0e15\u0e4c\u0e2e\u0e2d\u0e19\u0e14\u0e49\u0e32 \u0e04\u0e27\u0e49\u0e32\u0e2d\u0e35\u0e01 1 \u0e23\u0e32\u0e07\u0e27\u0e31\u0e25\u0e43\u0e2b\u0e0d\u0e48\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e01\u0e31\u0e1a\u0e23\u0e32\u0e07\u0e27\u0e31\u0e25 Thailand\u2019s Most Admired Brand 2023 \u0e40\u0e1b\u0e47\u0e19\u0e1b\u0e35\u0e17\u0e35\u0e48 18 \u0e15\u0e34\u0e14\u0e15\u0e48\u0e2d\u0e01\u0e31\u0e19 \u0e19\u0e31\u0e1a\u0e40\u0e1b\u0e47\u0e19\u0e40\u0e2a\u0e35\u0e22\u0e07\u0e15\u0e2d\u0e1a\u0e23\u0e31\u0e1a\u0e17\u0e35\u0e48\u0e14\u0e35\u0e40\u0e22\u0e35\u0e48\u0e22\u0e21\u0e08\u0e32\u0e01\u0e1c\u0e39\u0e49\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19\u0e17\u0e31\u0e48\u0e27\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e17\u0e35\u0e48\u0e43\u0e2b\u0e49\u0e04\u0e27\u0e32\u0e21\u0e44\u0e27\u0e49\u0e27\u0e32\u0e07\u0e43\u0e08\u0e2e\u0e2d\u0e19\u0e14\u0e49\u0e32\u0e21\u0e32\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e22\u0e32\u0e27\u0e19\u0e32\u0e19 \u0e1c\u0e48\u0e32\u0e19\u0e1c\u0e25\u0e01\u0e32\u0e23\u0e2a\u0e33\u0e23\u0e27\u0e08\u0e04\u0e27\u0e32\u0e21\u0e1e\u0e36\u0e07\u0e1e\u0e2d\u0e43\u0e08\u0e41\u0e25\u0e30\u0e04\u0e27\u0e32\u0e21\u0e40\u0e0a\u0e37\u0e48\u0e2d\u0e16\u0e37\u0e2d\u0e15\u0e48\u0e2d\u0e41\u0e1a\u0e23\u0e19\u0e14\u0e4c\u0e43\u0e19\u0e01\u0e25\u0e38\u0e48\u0e21\u0e23\u0e16\u0e08\u0e31\u0e01\u0e23\u0e22\u0e32\u0e19\u0e22\u0e19\u0e15\u0e4c \u0e42\u0e14\u0e22 BrandAge \u0e40\u0e21\u0e37\u0e48\u0e2d\u0e40\u0e23\u0e47\u0e27 \u0e46 \u0e19\u0e35\u0e49<\/p>\n<p><strong>\u0e19\u0e32\u0e07\u0e21\u0e19\u0e2a\u0e34\u0e0a\u0e32 \u0e2a\u0e31\u0e07\u0e02\u0e4c\u0e2a\u0e38\u0e27\u0e23\u0e23\u0e13 \u0e1c\u0e39\u0e49\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e17\u0e31\u0e48\u0e27\u0e44\u0e1b\u0e2a\u0e32\u0e22\u0e07\u0e32\u0e19\u0e01\u0e32\u0e23\u0e2a\u0e37\u0e48\u0e2d\u0e2a\u0e32\u0e23\u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14 \u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17 \u0e44\u0e17\u0e22\u0e2e\u0e2d\u0e19\u0e14\u0e49\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14<\/strong> \u0e01\u0e25\u0e48\u0e32\u0e27\u0e16\u0e36\u0e07\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e43\u0e19\u0e04\u0e23\u0e31\u0e49\u0e07\u0e19\u0e35\u0e49\u0e27\u0e48\u0e32 \u201c\u0e23\u0e16\u0e08\u0e31\u0e01\u0e23\u0e22\u0e32\u0e19\u0e22\u0e19\u0e15\u0e4c\u0e2e\u0e2d\u0e19\u0e14\u0e49\u0e32\u0e21\u0e38\u0e48\u0e07\u0e21\u0e31\u0e48\u0e19\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e44\u0e21\u0e48\u0e25\u0e14\u0e25\u0e30 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e43\u0e2b\u0e49\u0e04\u0e19\u0e44\u0e17\u0e22\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e1b\u0e23\u0e30\u0e2a\u0e1a\u0e01\u0e32\u0e23\u0e13\u0e4c\u0e01\u0e32\u0e23\u0e02\u0e31\u0e1a\u0e02\u0e35\u0e48\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19\u0e17\u0e35\u0e48\u0e14\u0e35\u0e40\u0e22\u0e35\u0e48\u0e22\u0e21\u0e21\u0e32\u0e01\u0e17\u0e35\u0e48\u0e2a\u0e38\u0e14 \u0e08\u0e36\u0e07\u0e40\u0e1b\u0e47\u0e19\u0e40\u0e2b\u0e15\u0e38\u0e1c\u0e25\u0e2a\u0e33\u0e04\u0e31\u0e0d \u0e17\u0e35\u0e48\u0e17\u0e33\u0e43\u0e2b\u0e49\u0e40\u0e23\u0e32\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e04\u0e27\u0e32\u0e21\u0e44\u0e27\u0e49\u0e27\u0e32\u0e07\u0e43\u0e08\u0e41\u0e25\u0e30\u0e04\u0e27\u0e32\u0e21\u0e1e\u0e36\u0e07\u0e1e\u0e2d\u0e43\u0e08\u0e08\u0e32\u0e01\u0e1c\u0e39\u0e49\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19\u0e21\u0e32\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e22\u0e32\u0e27\u0e19\u0e32\u0e19 18 \u0e1b\u0e35 \u0e41\u0e25\u0e30\u0e40\u0e1b\u0e47\u0e19\u0e1c\u0e39\u0e49\u0e19\u0e33\u0e43\u0e19\u0e15\u0e25\u0e32\u0e14\u0e15\u0e48\u0e2d\u0e40\u0e19\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e32\u0e16\u0e36\u0e07 34 \u0e1b\u0e35 \u0e43\u0e19\u0e02\u0e13\u0e30\u0e40\u0e14\u0e35\u0e22\u0e27\u0e01\u0e31\u0e19\u0e19\u0e2d\u0e01\u0e40\u0e2b\u0e19\u0e37\u0e2d\u0e08\u0e32\u0e01\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e23\u0e16\u0e08\u0e31\u0e01\u0e23\u0e22\u0e32\u0e19\u0e22\u0e19\u0e15\u0e4c \u0e40\u0e23\u0e32\u0e22\u0e31\u0e07\u0e21\u0e38\u0e48\u0e07\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e04\u0e38\u0e13\u0e20\u0e32\u0e1e\u0e0a\u0e35\u0e27\u0e34\u0e15\u0e02\u0e2d\u0e07\u0e04\u0e19\u0e44\u0e17\u0e22 \u0e1c\u0e48\u0e32\u0e19\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e2a\u0e31\u0e07\u0e04\u0e21\u0e41\u0e25\u0e30\u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e2a\u0e31\u0e07\u0e04\u0e21\u0e22\u0e31\u0e48\u0e07\u0e22\u0e37\u0e19\u0e15\u0e48\u0e32\u0e07\u0e46 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e43\u0e2b\u0e49\u0e04\u0e19\u0e44\u0e17\u0e22\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e04\u0e38\u0e13\u0e20\u0e32\u0e1e\u0e0a\u0e35\u0e27\u0e34\u0e15\u0e17\u0e35\u0e48\u0e14\u0e35\u0e17\u0e35\u0e48\u0e2a\u0e38\u0e14 \u0e41\u0e25\u0e30\u0e08\u0e32\u0e01\u0e1c\u0e25\u0e02\u0e2d\u0e07\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e43\u0e19\u0e04\u0e23\u0e31\u0e49\u0e07\u0e19\u0e35\u0e49\u0e08\u0e30\u0e40\u0e1b\u0e47\u0e19\u0e2d\u0e35\u0e01\u0e2b\u0e19\u0e36\u0e48\u0e07\u0e41\u0e23\u0e07\u0e1c\u0e25\u0e31\u0e01\u0e14\u0e31\u0e19\u0e17\u0e35\u0e48\u0e2a\u0e33\u0e04\u0e31\u0e0d\u0e43\u0e2b\u0e49\u0e40\u0e23\u0e32\u0e21\u0e38\u0e48\u0e07\u0e2b\u0e19\u0e49\u0e32\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e28\u0e31\u0e01\u0e22\u0e20\u0e32\u0e1e\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e44\u0e21\u0e48\u0e25\u0e14\u0e25\u0e30\u0e15\u0e48\u0e2d \u0e46 \u0e44\u0e1b\u201d<\/p>\n<p><strong>\u0e23\u0e32\u0e07\u0e27\u0e31\u0e25 Thailand\u2019s Most Admired Brand \u0e08\u0e32\u0e01 BrandAge<\/strong> \u0e19\u0e31\u0e1a\u0e40\u0e1b\u0e47\u0e19\u0e2b\u0e19\u0e36\u0e48\u0e07\u0e43\u0e19\u0e23\u0e32\u0e07\u0e27\u0e31\u0e25\u0e17\u0e35\u0e48\u0e2e\u0e2d\u0e19\u0e14\u0e49\u0e32\u0e20\u0e32\u0e04\u0e20\u0e39\u0e21\u0e34\u0e43\u0e08 \u0e40\u0e1e\u0e23\u0e32\u0e30\u0e40\u0e1b\u0e47\u0e19\u0e23\u0e32\u0e07\u0e27\u0e31\u0e25\u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14\u0e17\u0e35\u0e48\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e22\u0e2d\u0e21\u0e23\u0e31\u0e1a\u0e08\u0e32\u0e01\u0e04\u0e19\u0e44\u0e17\u0e22\u0e21\u0e32\u0e01\u0e17\u0e35\u0e48\u0e2a\u0e38\u0e14 \u0e0b\u0e36\u0e48\u0e07\u0e2a\u0e30\u0e17\u0e49\u0e2d\u0e19\u0e43\u0e2b\u0e49\u0e40\u0e2b\u0e47\u0e19\u0e16\u0e36\u0e07\u0e04\u0e27\u0e32\u0e21\u0e44\u0e27\u0e49\u0e27\u0e32\u0e07\u0e43\u0e08\u0e02\u0e2d\u0e07\u0e04\u0e19\u0e44\u0e17\u0e22\u0e17\u0e35\u0e48\u0e21\u0e35\u0e15\u0e48\u0e2d\u0e41\u0e1a\u0e23\u0e19\u0e14\u0e4c \u0e08\u0e32\u0e01\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21 \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e21\u0e32\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e15\u0e48\u0e2d\u0e40\u0e19\u0e37\u0e48\u0e2d\u0e07 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e43\u0e2b\u0e49\u0e04\u0e19\u0e44\u0e17\u0e22\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e04\u0e27\u0e32\u0e21\u0e1e\u0e36\u0e07\u0e1e\u0e2d\u0e43\u0e08\u0e21\u0e32\u0e01\u0e17\u0e35\u0e48\u0e2a\u0e38\u0e14<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u0e23\u0e16\u0e08\u0e31\u0e01\u0e23\u0e22\u0e32\u0e19\u0e22\u0e19\u0e15\u0e4c\u0e2e\u0e2d\u0e19\u0e14\u0e49\u0e32 \u0e04\u0e27\u0e49\u0e32\u0e2d\u0e35\u0e01 1 \u0e23\u0e32\u0e07\u0e27\u0e31\u0e25\u0e43\u0e2b\u0e0d\u0e48\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e01\u0e31\u0e1a\u0e23\u0e32\u0e07\u0e27\u0e31\u0e25 Thailand\u2019s Most Admired Brand 2023 \u0e40\u0e1b\u0e47\u0e19\u0e1b\u0e35\u0e17\u0e35\u0e48 18 \u0e15\u0e34\u0e14\u0e15\u0e48\u0e2d\u0e01\u0e31\u0e19 \u0e19\u0e31\u0e1a\u0e40\u0e1b\u0e47\u0e19\u0e40\u0e2a\u0e35\u0e22\u0e07\u0e15\u0e2d\u0e1a\u0e23\u0e31\u0e1a\u0e17\u0e35\u0e48\u0e14\u0e35\u0e40\u0e22\u0e35\u0e48\u0e22\u0e21\u0e08\u0e32\u0e01\u0e1c\u0e39\u0e49\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19\u0e17\u0e31\u0e48\u0e27\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e17\u0e35\u0e48\u0e43\u0e2b\u0e49\u0e04\u0e27\u0e32\u0e21\u0e44\u0e27\u0e49\u0e27\u0e32\u0e07\u0e43\u0e08\u0e2e\u0e2d\u0e19\u0e14\u0e49\u0e32\u0e21\u0e32\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e22\u0e32\u0e27\u0e19\u0e32\u0e19 \u0e1c\u0e48\u0e32\u0e19\u0e1c\u0e25\u0e01\u0e32\u0e23\u0e2a\u0e33\u0e23\u0e27\u0e08\u0e04\u0e27\u0e32\u0e21\u0e1e\u0e36\u0e07\u0e1e\u0e2d\u0e43\u0e08\u0e41\u0e25\u0e30\u0e04\u0e27\u0e32\u0e21\u0e40\u0e0a\u0e37\u0e48\u0e2d\u0e16\u0e37\u0e2d\u0e15\u0e48\u0e2d\u0e41\u0e1a\u0e23\u0e19\u0e14\u0e4c\u0e43\u0e19\u0e01\u0e25\u0e38\u0e48\u0e21\u0e23\u0e16\u0e08\u0e31\u0e01\u0e23\u0e22\u0e32\u0e19\u0e22\u0e19\u0e15\u0e4c \u0e42\u0e14\u0e22 BrandAge \u0e40\u0e21\u0e37\u0e48\u0e2d\u0e40\u0e23\u0e47\u0e27 \u0e46 \u0e19\u0e35\u0e49 \u0e19\u0e32\u0e07\u0e21\u0e19\u0e2a\u0e34\u0e0a\u0e32<\/p>\n","protected":false},"author":3,"featured_media":107775,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","footnotes":""},"categories":[3],"tags":[1200],"class_list":["post-107774","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-car","tag-1200"],"_links":{"self":[{"href":"https:\/\/www.benewsonline.com\/home\/wp-json\/wp\/v2\/posts\/107774","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.benewsonline.com\/home\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.benewsonline.com\/home\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.benewsonline.com\/home\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.benewsonline.com\/home\/wp-json\/wp\/v2\/comments?post=107774"}],"version-history":[{"count":1,"href":"https:\/\/www.benewsonline.com\/home\/wp-json\/wp\/v2\/posts\/107774\/revisions"}],"predecessor-version":[{"id":107776,"href":"https:\/\/www.benewsonline.com\/home\/wp-json\/wp\/v2\/posts\/107774\/revisions\/107776"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.benewsonline.com\/home\/wp-json\/wp\/v2\/media\/107775"}],"wp:attachment":[{"href":"https:\/\/www.benewsonline.com\/home\/wp-json\/wp\/v2\/media?parent=107774"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.benewsonline.com\/home\/wp-json\/wp\/v2\/categories?post=107774"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.benewsonline.com\/home\/wp-json\/wp\/v2\/tags?post=107774"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}