{"id":101608,"date":"2022-10-08T21:58:22","date_gmt":"2022-10-08T14:58:22","guid":{"rendered":"https:\/\/www.benewsonline.com\/home\/?p=101608"},"modified":"2022-10-08T21:58:22","modified_gmt":"2022-10-08T14:58:22","slug":"%e0%b9%84%e0%b8%97%e0%b8%a2%e0%b8%ae%e0%b8%ad%e0%b8%99%e0%b8%94%e0%b9%89%e0%b8%b2-%e0%b8%9b%e0%b8%a3%e0%b8%b0%e0%b8%81%e0%b8%b2%e0%b8%a8%e0%b8%9c%e0%b8%a5-h2c-motorbike-idea-challenge-2022-%e0%b9%83","status":"publish","type":"post","link":"https:\/\/www.benewsonline.com\/home\/2022\/10\/%e0%b9%84%e0%b8%97%e0%b8%a2%e0%b8%ae%e0%b8%ad%e0%b8%99%e0%b8%94%e0%b9%89%e0%b8%b2-%e0%b8%9b%e0%b8%a3%e0%b8%b0%e0%b8%81%e0%b8%b2%e0%b8%a8%e0%b8%9c%e0%b8%a5-h2c-motorbike-idea-challenge-2022-%e0%b9%83\/","title":{"rendered":"\u0e44\u0e17\u0e22\u0e2e\u0e2d\u0e19\u0e14\u0e49\u0e32 \u0e1b\u0e23\u0e30\u0e01\u0e32\u0e28\u0e1c\u0e25 H2C Motorbike Idea Challenge 2022 \u0e43\u0e19\u0e23\u0e38\u0e48\u0e19 Honda ADV350"},"content":{"rendered":"<p>\u0e44\u0e17\u0e22\u0e2e\u0e2d\u0e19\u0e14\u0e49\u0e32 \u0e08\u0e31\u0e14\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21 H2C Motor Bike Idea Challenge 2022 \u0e1b\u0e23\u0e30\u0e01\u0e27\u0e14\u0e44\u0e2d\u0e40\u0e14\u0e35\u0e22\u0e15\u0e01\u0e41\u0e15\u0e48\u0e07\u0e23\u0e16\u0e08\u0e31\u0e01\u0e23\u0e22\u0e32\u0e19\u0e22\u0e19\u0e15\u0e4c \u0e42\u0e14\u0e22\u0e21\u0e35\u0e01\u0e2d\u0e07\u0e17\u0e31\u0e1e\u0e23\u0e16\u0e41\u0e15\u0e48\u0e07\u0e43\u0e19\u0e23\u0e38\u0e48\u0e19 Honda ADV350 \u0e41\u0e25\u0e30 Honda DAX125 \u0e21\u0e32\u0e01\u0e01\u0e27\u0e48\u0e32 40 \u0e04\u0e31\u0e19 \u0e41\u0e15\u0e48\u0e25\u0e30\u0e04\u0e31\u0e19\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e15\u0e01\u0e41\u0e15\u0e48\u0e07\u0e04\u0e31\u0e2a\u0e15\u0e2d\u0e21\u0e43\u0e19\u0e2a\u0e44\u0e15\u0e25\u0e4c\u0e17\u0e35\u0e48\u0e41\u0e15\u0e01\u0e15\u0e48\u0e32\u0e07 \u0e08\u0e32\u0e01\u0e2a\u0e38\u0e14\u0e22\u0e2d\u0e14\u0e1d\u0e35\u0e21\u0e37\u0e2d\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e41\u0e15\u0e48\u0e07\u0e0a\u0e31\u0e49\u0e19\u0e19\u0e33\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e01\u0e27\u0e48\u0e32 40 \u0e41\u0e2b\u0e48\u0e07\u0e17\u0e35\u0e48\u0e40\u0e02\u0e49\u0e32\u0e23\u0e48\u0e27\u0e21\u0e1b\u0e23\u0e30\u0e01\u0e27\u0e14\u0e43\u0e19\u0e04\u0e23\u0e31\u0e49\u0e07\u0e19\u0e35\u0e49 \u0e43\u0e19\u0e07\u0e32\u0e19\u0e44\u0e17\u0e22\u0e41\u0e25\u0e19\u0e14\u0e4c \u0e08\u0e35\u0e1e\u0e35 2022 \u0e17\u0e35\u0e48\u0e2a\u0e19\u0e32\u0e21\u0e0a\u0e49\u0e32\u0e07 \u0e2d\u0e34\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e40\u0e19\u0e0a\u0e31\u0e48\u0e19\u0e41\u0e19\u0e25 \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e01\u0e34\u0e15 \u0e08.\u0e1a\u0e38\u0e23\u0e35\u0e23\u0e31\u0e21\u0e22\u0e4c<\/p>\n<p><strong>\u0e04\u0e38\u0e13\u0e13\u0e31\u0e10\u0e0a\u0e31\u0e22 \u0e28\u0e23\u0e35\u0e42\u0e2a\u0e27\u0e23\u0e23\u0e13\u0e32 \u0e2b\u0e31\u0e27\u0e2b\u0e19\u0e49\u0e32\u0e40\u0e08\u0e49\u0e32\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23 \u0e01\u0e25\u0e38\u0e48\u0e21\u0e07\u0e32\u0e19\u0e27\u0e32\u0e07\u0e41\u0e1c\u0e19\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08 \u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17 \u0e44\u0e17\u0e22\u0e2e\u0e2d\u0e19\u0e14\u0e49\u0e32 \u0e08\u0e4d\u0e32\u0e01\u0e31\u0e14<\/strong> \u0e40\u0e1b\u0e34\u0e14\u0e40\u0e1c\u0e22\u0e27\u0e48\u0e32 \u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21 H2C Motor Bike Idea Challenge \u0e40\u0e01\u0e34\u0e14\u0e08\u0e32\u0e01\u0e01\u0e25\u0e38\u0e48\u0e21\u0e04\u0e19\u0e17\u0e35\u0e48\u0e04\u0e25\u0e31\u0e48\u0e07\u0e44\u0e04\u0e25\u0e49\u0e43\u0e19\u0e01\u0e32\u0e23\u0e41\u0e15\u0e48\u0e07\u0e23\u0e16\u0e08\u0e31\u0e01\u0e23\u0e22\u0e32\u0e19\u0e22\u0e19\u0e15\u0e4c Honda Two Wheels Customized \u0e2b\u0e23\u0e37\u0e2d H2C \u0e0b\u0e36\u0e48\u0e07\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e19\u0e35\u0e49\u0e08\u0e31\u0e14\u0e02\u0e36\u0e49\u0e19\u0e15\u0e48\u0e2d\u0e40\u0e19\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e32\u0e01\u0e27\u0e48\u0e32 10 \u0e1b\u0e35 \u0e41\u0e25\u0e30\u0e43\u0e19\u0e43\u0e19\u0e1b\u0e35\u0e19\u0e35\u0e49\u0e44\u0e14\u0e49\u0e08\u0e31\u0e14\u0e41\u0e2a\u0e14\u0e07\u0e23\u0e16\u0e41\u0e15\u0e48\u0e07 Honda ADV350 \u0e0b\u0e36\u0e48\u0e07\u0e40\u0e1b\u0e47\u0e19\u0e23\u0e16 Premium SUV Bike \u0e17\u0e35\u0e48\u0e23\u0e2d\u0e07\u0e23\u0e31\u0e1a\u0e44\u0e25\u0e1f\u0e4c\u0e2a\u0e44\u0e15\u0e25\u0e4c\u0e43\u0e19\u0e41\u0e1a\u0e1a\u0e41\u0e2d\u0e14\u0e40\u0e27\u0e19\u0e40\u0e08\u0e2d\u0e23\u0e4c\u0e41\u0e25\u0e30\u0e2a\u0e1b\u0e2d\u0e23\u0e4c\u0e15 \u0e41\u0e25\u0e30 Honda DAX125 \u0e15\u0e31\u0e27\u0e41\u0e2a\u0e1a \u0e08\u0e2d\u0e21\u0e0b\u0e48\u0e32\u0e2a\u0e4c \u0e08\u0e49\u0e32\u0e27\u0e41\u0e2b\u0e48\u0e07\u0e04\u0e27\u0e32\u0e21\u0e17\u0e49\u0e32\u0e17\u0e32\u0e22<\/p>\n<p style=\"text-align: center;\"><a href=\"https:\/\/www.benewsonline.com\/wp-content\/uploads\/2022\/10\/11.jpg\"><img fetchpriority=\"high\" decoding=\"async\" class=\"alignnone size-large wp-image-101610\" src=\"https:\/\/www.benewsonline.com\/wp-content\/uploads\/2022\/10\/11-1024x682.jpg\" alt=\"\" width=\"800\" height=\"533\" srcset=\"https:\/\/www.benewsonline.com\/wp-content\/uploads\/2022\/10\/11-1024x682.jpg 1024w, https:\/\/www.benewsonline.com\/wp-content\/uploads\/2022\/10\/11-300x200.jpg 300w, https:\/\/www.benewsonline.com\/wp-content\/uploads\/2022\/10\/11-768x511.jpg 768w, https:\/\/www.benewsonline.com\/wp-content\/uploads\/2022\/10\/11-1536x1023.jpg 1536w, https:\/\/www.benewsonline.com\/wp-content\/uploads\/2022\/10\/11.jpg 1568w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/a><\/p>\n<p>\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e01\u0e27\u0e14 H2C Motor Bike Idea Challenge \u0e41\u0e1a\u0e48\u0e07\u0e40\u0e1b\u0e47\u0e19 2 \u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17\u0e23\u0e32\u0e07\u0e27\u0e31\u0e25 \u0e44\u0e14\u0e49\u0e41\u0e01\u0e48 \u0e23\u0e32\u0e07\u0e27\u0e31\u0e25\u0e0a\u0e19\u0e30\u0e40\u0e25\u0e34\u0e28 Honda ADV350 \u0e08\u0e33\u0e19\u0e27\u0e19 9 \u0e23\u0e32\u0e07\u0e27\u0e31\u0e25 \u0e41\u0e25\u0e30 \u0e23\u0e32\u0e07\u0e27\u0e31\u0e25\u0e0a\u0e19\u0e30\u0e40\u0e25\u0e34\u0e28 Honda DAX125 \u0e08\u0e33\u0e19\u0e27\u0e19 9 \u0e23\u0e32\u0e07\u0e27\u0e31\u0e25 \u0e42\u0e14\u0e22\u0e1c\u0e39\u0e49\u0e0a\u0e19\u0e30\u0e40\u0e25\u0e34\u0e28\u0e08\u0e30\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a \u0e16\u0e49\u0e27\u0e22\u0e23\u0e32\u0e07\u0e27\u0e31\u0e25\u0e40\u0e01\u0e35\u0e22\u0e23\u0e15\u0e34\u0e22\u0e28\u0e08\u0e32\u0e01\u0e17\u0e32\u0e07 \u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17 \u0e44\u0e17\u0e22\u0e2e\u0e2d\u0e19\u0e14\u0e49\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14 \u0e41\u0e1e\u0e04\u0e40\u0e01\u0e08\u0e17\u0e48\u0e2d\u0e07\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27 Exclusive Trip \u0e21\u0e39\u0e25\u0e04\u0e48\u0e32 \u0e23\u0e32\u0e07\u0e27\u0e31\u0e25\u0e25\u0e30 60,000 \u0e1a\u0e32\u0e17 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e2b\u0e21\u0e14 18 \u0e23\u0e32\u0e07\u0e27\u0e31\u0e25 \u0e21\u0e39\u0e25\u0e04\u0e48\u0e32\u0e02\u0e2d\u0e07\u0e23\u0e32\u0e07\u0e27\u0e31\u0e25 \u0e21\u0e32\u0e01\u0e01\u0e27\u0e48\u0e32 1 \u0e25\u0e49\u0e32\u0e19\u0e1a\u0e32\u0e17<\/p>\n<p>\u0e2a\u0e48\u0e27\u0e19\u0e43\u0e19\u0e23\u0e38\u0e48\u0e19 Honda DAX125 \u0e08\u0e30\u0e21\u0e35\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e01\u0e32\u0e28\u0e1c\u0e25\u0e23\u0e32\u0e07\u0e27\u0e31\u0e25\u0e17\u0e35\u0e48\u0e07\u0e32\u0e19 BANGKOK HOT ROD CUSTOM SHOW 2022\u00a0 \u0e17\u0e35\u0e48\u0e08\u0e30\u0e08\u0e31\u0e14\u0e02\u0e36\u0e49\u0e19\u0e43\u0e19\u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 4-6 \u0e1e\u0e24\u0e28\u0e08\u0e34\u0e01\u0e32\u0e22\u0e19 \u0e19\u0e35\u0e49 \u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e23\u0e48\u0e27\u0e21\u0e25\u0e38\u0e49\u0e19 \u0e23\u0e48\u0e27\u0e21\u0e40\u0e0a\u0e35\u0e22\u0e23\u0e4c\u0e01\u0e31\u0e19\u0e44\u0e14\u0e49 \u0e0b\u0e36\u0e48\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19\u0e07\u0e32\u0e19\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u0e44\u0e17\u0e22\u0e2e\u0e2d\u0e19\u0e14\u0e49\u0e32\u0e44\u0e14\u0e49\u0e40\u0e15\u0e23\u0e35\u0e22\u0e21\u0e22\u0e01\u0e02\u0e1a\u0e27\u0e19 Honda DAX125 \u0e44\u0e1b\u0e23\u0e48\u0e27\u0e21\u0e07\u0e32\u0e19\u0e19\u0e35\u0e49\u0e14\u0e49\u0e27\u0e22\u0e40\u0e0a\u0e48\u0e19\u0e40\u0e14\u0e35\u0e22\u0e27\u0e01\u0e31\u0e19<\/p>\n<p>\u0e15\u0e34\u0e14\u0e15\u0e32\u0e21\u0e1b\u0e23\u0e30\u0e01\u0e32\u0e28\u0e1c\u0e25\u0e23\u0e32\u0e07\u0e27\u0e31\u0e25\u0e0a\u0e19\u0e30\u0e40\u0e25\u0e34\u0e28 H2C Motorbike Idea Challenge 2022 \u0e17\u0e31\u0e49\u0e07 9 \u0e23\u0e32\u0e07\u0e27\u0e31\u0e25 \u0e02\u0e2d\u0e07\u0e23\u0e38\u0e48\u0e19 Honda ADV350 \u0e44\u0e14\u0e49\u0e17\u0e35\u0e48\u0e40\u0e1f\u0e0b\u0e1a\u0e38\u0e4a\u0e01\u0e23\u0e16\u0e08\u0e31\u0e01\u0e23\u0e22\u0e32\u0e19\u0e22\u0e19\u0e15\u0e4c\u0e2e\u0e2d\u0e19\u0e14\u0e49\u0e32 <a href=\"https:\/\/facebook.com\/story.php?story_fbid=5506369762744797&amp;id=146961768685650\">https:\/\/facebook.com\/story.php?story_fbid=5506369762744797&amp;id=146961768685650<\/a><\/p>\n<p>#H2CMotorBikeideaChallenge #NewADV350 #ADV350 #HondaDax #Dax125 #H2C #\u0e23\u0e16\u0e08\u0e31\u0e01\u0e23\u0e22\u0e32\u0e19\u0e22\u0e19\u0e15\u0e4c\u0e2e\u0e2d\u0e19\u0e14\u0e49\u0e32 #WhatstopsYou<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u0e44\u0e17\u0e22\u0e2e\u0e2d\u0e19\u0e14\u0e49\u0e32 \u0e08\u0e31\u0e14\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21 H2C Motor Bike Idea Challenge 2022 \u0e1b\u0e23\u0e30\u0e01\u0e27\u0e14\u0e44\u0e2d\u0e40\u0e14\u0e35\u0e22\u0e15\u0e01\u0e41\u0e15\u0e48\u0e07\u0e23\u0e16\u0e08\u0e31\u0e01\u0e23\u0e22\u0e32\u0e19\u0e22\u0e19\u0e15\u0e4c \u0e42\u0e14\u0e22\u0e21\u0e35\u0e01\u0e2d\u0e07\u0e17\u0e31\u0e1e\u0e23\u0e16\u0e41\u0e15\u0e48\u0e07\u0e43\u0e19\u0e23\u0e38\u0e48\u0e19 Honda ADV350 \u0e41\u0e25\u0e30 Honda DAX125 \u0e21\u0e32\u0e01\u0e01\u0e27\u0e48\u0e32 40 \u0e04\u0e31\u0e19 \u0e41\u0e15\u0e48\u0e25\u0e30\u0e04\u0e31\u0e19\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e15\u0e01\u0e41\u0e15\u0e48\u0e07\u0e04\u0e31\u0e2a\u0e15\u0e2d\u0e21\u0e43\u0e19\u0e2a\u0e44\u0e15\u0e25\u0e4c\u0e17\u0e35\u0e48\u0e41\u0e15\u0e01\u0e15\u0e48\u0e32\u0e07 \u0e08\u0e32\u0e01\u0e2a\u0e38\u0e14\u0e22\u0e2d\u0e14\u0e1d\u0e35\u0e21\u0e37\u0e2d\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e41\u0e15\u0e48\u0e07\u0e0a\u0e31\u0e49\u0e19\u0e19\u0e33\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e01\u0e27\u0e48\u0e32<\/p>\n","protected":false},"author":3,"featured_media":101609,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","footnotes":""},"categories":[3],"tags":[2308],"class_list":["post-101608","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-car","tag-2308"],"_links":{"self":[{"href":"https:\/\/www.benewsonline.com\/home\/wp-json\/wp\/v2\/posts\/101608","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.benewsonline.com\/home\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.benewsonline.com\/home\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.benewsonline.com\/home\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.benewsonline.com\/home\/wp-json\/wp\/v2\/comments?post=101608"}],"version-history":[{"count":1,"href":"https:\/\/www.benewsonline.com\/home\/wp-json\/wp\/v2\/posts\/101608\/revisions"}],"predecessor-version":[{"id":101611,"href":"https:\/\/www.benewsonline.com\/home\/wp-json\/wp\/v2\/posts\/101608\/revisions\/101611"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.benewsonline.com\/home\/wp-json\/wp\/v2\/media\/101609"}],"wp:attachment":[{"href":"https:\/\/www.benewsonline.com\/home\/wp-json\/wp\/v2\/media?parent=101608"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.benewsonline.com\/home\/wp-json\/wp\/v2\/categories?post=101608"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.benewsonline.com\/home\/wp-json\/wp\/v2\/tags?post=101608"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}