{"id":100053,"date":"2022-08-26T20:50:37","date_gmt":"2022-08-26T13:50:37","guid":{"rendered":"https:\/\/www.benewsonline.com\/home\/?p=100053"},"modified":"2022-08-26T20:50:37","modified_gmt":"2022-08-26T13:50:37","slug":"mercedes-benz-%e0%b8%aa%e0%b9%88%e0%b8%87%e0%b8%a1%e0%b8%ad%e0%b8%9a%e0%b8%a3%e0%b8%96%e0%b8%a2%e0%b8%99%e0%b8%95%e0%b9%8c-mercedes-benz-s-350-d-exclusive-%e0%b9%80%e0%b8%aa%e0%b8%a3","status":"publish","type":"post","link":"https:\/\/www.benewsonline.com\/home\/2022\/08\/mercedes-benz-%e0%b8%aa%e0%b9%88%e0%b8%87%e0%b8%a1%e0%b8%ad%e0%b8%9a%e0%b8%a3%e0%b8%96%e0%b8%a2%e0%b8%99%e0%b8%95%e0%b9%8c-mercedes-benz-s-350-d-exclusive-%e0%b9%80%e0%b8%aa%e0%b8%a3\/","title":{"rendered":"Mercedes-Benz \u0e2a\u0e48\u0e07\u0e21\u0e2d\u0e1a\u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c \u201cMercedes-Benz S 350 d Exclusive\u201d \u0e40\u0e2a\u0e23\u0e34\u0e21\u0e17\u0e31\u0e1e\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e23\u0e30\u0e14\u0e31\u0e1a 6 \u0e14\u0e32\u0e27\u0e43\u0e2b\u0e49\u0e01\u0e31\u0e1a\u0e42\u0e23\u0e07\u0e41\u0e23\u0e21 \u0e40\u0e14\u0e2d\u0e30 \u0e40\u0e0b\u0e19\u0e15\u0e4c \u0e23\u0e35\u0e08\u0e34\u0e2a \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e2f"},"content":{"rendered":"<p><strong>\u0e21\u0e23. \u0e1a\u0e35\u0e40\u0e22\u0e34\u0e23\u0e4c\u0e19 \u0e01\u0e38\u0e0b\u0e40\u0e17\u0e23\u0e32 <\/strong>(\u0e17\u0e35\u0e48 2 \u0e08\u0e32\u0e01\u0e0b\u0e49\u0e32\u0e22) \u0e23\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e18\u0e32\u0e19\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e1d\u0e48\u0e32\u0e22\u0e02\u0e32\u0e22\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14 \u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17 \u0e40\u0e21\u0e2d\u0e23\u0e4c\u0e40\u0e0b\u0e40\u0e14\u0e2a-\u0e40\u0e1a\u0e19\u0e0b\u0e4c (\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22) \u0e08\u0e33\u0e01\u0e31\u0e14 \u0e2a\u0e48\u0e07\u0e21\u0e2d\u0e1a\u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c \u201cMercedes-Benz S 350 d Exclusive\u201d \u0e08\u0e33\u0e19\u0e27\u0e19 6 \u0e04\u0e31\u0e19 \u0e43\u0e2b\u0e49\u0e01\u0e31\u0e1a <strong>\u0e21\u0e23.<\/strong><strong>\u0e40\u0e04\u0e25\u0e32\u0e2a\u0e4c \u0e04\u0e23\u0e34\u0e2a\u0e15\u0e31\u0e19\u0e40\u0e14\u0e34\u0e25 <\/strong>(\u0e17\u0e35\u0e48 2 \u0e08\u0e32\u0e01\u0e02\u0e27\u0e32) \u0e1c\u0e39\u0e49\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e17\u0e31\u0e48\u0e27\u0e44\u0e1b \u0e42\u0e23\u0e07\u0e41\u0e23\u0e21 \u0e40\u0e14\u0e2d\u0e30 \u0e40\u0e0b\u0e19\u0e15\u0e4c \u0e23\u0e35\u0e08\u0e34\u0e2a \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e2f \u0e42\u0e14\u0e22\u0e21\u0e35 <strong>\u0e21\u0e23.\u0e41\u0e0b\u0e21 \u0e40\u0e09\u0e35\u0e22 <\/strong>(\u0e02\u0e27\u0e32\u0e2a\u0e38\u0e14) \u0e23\u0e2d\u0e07\u0e1c\u0e39\u0e49\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e0d\u0e48 \u0e42\u0e23\u0e07\u0e41\u0e23\u0e21 \u0e40\u0e14\u0e2d\u0e30 \u0e40\u0e0b\u0e19\u0e15\u0e4c \u0e23\u0e35\u0e08\u0e34\u0e2a \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e2f <strong>\u0e19\u0e32\u0e07\u0e1b\u0e31\u0e0d\u0e08\u0e27\u0e34\u0e44\u0e25 \u0e2a\u0e07\u0e04\u0e4c\u0e2d\u0e34\u0e48\u0e21 <\/strong>(\u0e01\u0e25\u0e32\u0e07) \u0e01\u0e23\u0e23\u0e21\u0e01\u0e32\u0e23\u0e1c\u0e39\u0e49\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23 \u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17 \u0e42\u0e2d\u0e40\u0e23\u0e35\u0e22\u0e19\u0e40\u0e15\u0e47\u0e25\u0e17\u0e23\u0e32\u0e19\u0e0b\u0e4c \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e04\u0e32\u0e23\u0e4c \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e0b \u0e08\u0e33\u0e01\u0e31\u0e14 \u0e1c\u0e39\u0e49\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e23\u0e16\u0e25\u0e34\u0e21\u0e39\u0e0b\u0e35\u0e19\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e42\u0e23\u0e07\u0e41\u0e23\u0e21\u0e0a\u0e31\u0e49\u0e19\u0e19\u0e33\u0e02\u0e2d\u0e07\u0e40\u0e21\u0e37\u0e2d\u0e07\u0e44\u0e17\u0e22 \u0e41\u0e25\u0e30<strong>\u0e19\u0e32\u0e22\u0e01\u0e23\u0e01\u0e0e\u00a0 \u0e27\u0e32\u0e23\u0e27\u0e34\u0e08\u0e34\u0e15\u0e23<\/strong> (\u0e0b\u0e49\u0e32\u0e22\u0e2a\u0e38\u0e14) \u0e1c\u0e39\u0e49\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e17\u0e31\u0e48\u0e27\u0e44\u0e1b\u0e1d\u0e48\u0e32\u0e22\u0e02\u0e32\u0e22\u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c<\/p>\n<p>\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17 \u0e40\u0e21\u0e2d\u0e23\u0e4c\u0e40\u0e0b\u0e40\u0e14\u0e2a-\u0e40\u0e1a\u0e19\u0e0b\u0e4c (\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22) \u0e08\u0e33\u0e01\u0e31\u0e14 \u0e23\u0e48\u0e27\u0e21\u0e40\u0e1b\u0e47\u0e19\u0e2a\u0e31\u0e01\u0e02\u0e35\u0e1e\u0e22\u0e32\u0e19\u0e43\u0e19\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e21\u0e2d\u0e1a\u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c\u0e40\u0e21\u0e2d\u0e23\u0e4c\u0e40\u0e0b\u0e40\u0e14\u0e2a-\u0e40\u0e1a\u0e19\u0e0b\u0e4c \u0e40\u0e2d\u0e2a \u0e04\u0e25\u0e32\u0e2a\u0e23\u0e38\u0e48\u0e19\u0e43\u0e2b\u0e21\u0e48 \u0e0b\u0e36\u0e48\u0e07\u0e42\u0e23\u0e07\u0e41\u0e23\u0e21 \u0e40\u0e14\u0e2d\u0e30 \u0e40\u0e0b\u0e19\u0e15\u0e4c \u0e23\u0e35\u0e08\u0e34\u0e2a \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e2f \u0e40\u0e25\u0e37\u0e2d\u0e01\u0e43\u0e0a\u0e49\u0e40\u0e1b\u0e47\u0e19\u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c\u0e19\u0e31\u0e48\u0e07\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e41\u0e02\u0e01\u0e1c\u0e39\u0e49\u0e40\u0e02\u0e49\u0e32\u0e1e\u0e31\u0e01\u0e43\u0e19\u0e42\u0e23\u0e07\u0e41\u0e23\u0e21 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e22\u0e01\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e21\u0e2d\u0e1a\u0e17\u0e31\u0e49\u0e07\u0e04\u0e27\u0e32\u0e21\u0e2b\u0e23\u0e39\u0e2b\u0e23\u0e32\u0e41\u0e25\u0e30\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e30\u0e14\u0e27\u0e01\u0e2a\u0e1a\u0e32\u0e22\u0e22\u0e34\u0e48\u0e07\u0e02\u0e36\u0e49\u0e19\u0e43\u0e2b\u0e49\u0e01\u0e31\u0e1a\u0e17\u0e38\u0e01\u0e04\u0e19<\/p>\n<p><strong>Mercedes-Benz S 350 d Exclusive<\/strong> \u0e40\u0e1b\u0e47\u0e19\u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c\u0e23\u0e38\u0e48\u0e19\u0e43\u0e2b\u0e21\u0e48\u0e40\u0e08\u0e40\u0e19\u0e2d\u0e40\u0e23\u0e0a\u0e31\u0e19\u0e25\u0e48\u0e32\u0e2a\u0e38\u0e14\u0e43\u0e19\u0e04\u0e23\u0e2d\u0e1a\u0e04\u0e23\u0e31\u0e27\u0e40\u0e21\u0e2d\u0e23\u0e4c\u0e40\u0e0b\u0e40\u0e14\u0e2a-\u0e40\u0e1a\u0e19\u0e0b\u0e4c \u0e40\u0e2d\u0e2a\u0e04\u0e25\u0e32\u0e2a \u0e17\u0e35\u0e48\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e19\u0e33\u0e40\u0e2a\u0e19\u0e2d\u0e1b\u0e23\u0e30\u0e2a\u0e1a\u0e01\u0e32\u0e23\u0e13\u0e4c\u0e01\u0e32\u0e23\u0e02\u0e31\u0e1a\u0e02\u0e35\u0e48\u0e17\u0e35\u0e48\u0e14\u0e35\u0e17\u0e35\u0e48\u0e2a\u0e38\u0e14\u0e20\u0e32\u0e22\u0e43\u0e15\u0e49\u0e04\u0e27\u0e32\u0e21\u0e2b\u0e23\u0e39\u0e2b\u0e23\u0e32 \u0e04\u0e27\u0e32\u0e21\u0e2a\u0e30\u0e14\u0e27\u0e01\u0e2a\u0e1a\u0e32\u0e22 \u0e41\u0e25\u0e30\u0e04\u0e27\u0e32\u0e21\u0e1b\u0e25\u0e2d\u0e14\u0e20\u0e31\u0e22\u0e02\u0e31\u0e49\u0e19\u0e2a\u0e39\u0e07\u0e2a\u0e38\u0e14 \u0e14\u0e49\u0e27\u0e22\u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21\u0e2a\u0e38\u0e14\u0e25\u0e49\u0e33\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48\u0e43\u0e2b\u0e49\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e33\u0e04\u0e31\u0e0d\u0e01\u0e31\u0e1a\u0e1c\u0e39\u0e49\u0e43\u0e0a\u0e49 \u0e01\u0e31\u0e1a\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e22\u0e19\u0e15\u0e4c\u0e14\u0e35\u0e40\u0e0b\u0e25\u0e17\u0e35\u0e48\u0e21\u0e35\u0e1b\u0e23\u0e30\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e20\u0e32\u0e1e\u0e21\u0e32\u0e01\u0e02\u0e36\u0e49\u0e19\u0e41\u0e25\u0e30\u0e40\u0e1b\u0e47\u0e19\u0e21\u0e34\u0e15\u0e23\u0e15\u0e48\u0e2d\u0e2a\u0e34\u0e48\u0e07\u0e41\u0e27\u0e14\u0e25\u0e49\u0e2d\u0e21\u0e22\u0e34\u0e48\u0e07\u0e02\u0e36\u0e49\u0e19 \u0e01\u0e32\u0e23\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a\u0e17\u0e31\u0e49\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19\u0e41\u0e25\u0e30\u0e20\u0e32\u0e22\u0e19\u0e2d\u0e01\u0e43\u0e2b\u0e21\u0e48\u0e2b\u0e21\u0e14\u0e08\u0e14 \u0e20\u0e32\u0e22\u0e43\u0e15\u0e49\u0e04\u0e2d\u0e19\u0e40\u0e0b\u0e47\u0e1b\u0e15\u0e4c Sensual Purity \u0e43\u0e19\u0e20\u0e32\u0e29\u0e32\u0e14\u0e35\u0e44\u0e0b\u0e19\u0e4c\u0e17\u0e35\u0e48\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e22\u0e01\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e02\u0e36\u0e49\u0e19\u0e43\u0e19\u0e17\u0e38\u0e01 \u0e46 \u0e2a\u0e48\u0e27\u0e19 \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e15\u0e2d\u0e1a\u0e23\u0e31\u0e1a\u0e04\u0e27\u0e32\u0e21\u0e15\u0e49\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e02\u0e2d\u0e07\u0e1c\u0e39\u0e49\u0e42\u0e14\u0e22\u0e2a\u0e32\u0e23\u0e43\u0e19\u0e17\u0e38\u0e01\u0e17\u0e35\u0e48\u0e19\u0e31\u0e48\u0e07\u0e14\u0e49\u0e27\u0e22\u0e1b\u0e23\u0e30\u0e2a\u0e1a\u0e01\u0e32\u0e23\u0e13\u0e4c\u0e14\u0e34\u0e08\u0e34\u0e17\u0e31\u0e25\u0e17\u0e35\u0e48\u0e40\u0e1b\u0e47\u0e19\u0e17\u0e35\u0e48\u0e2a\u0e38\u0e14 \u0e42\u0e14\u0e22\u0e40\u0e09\u0e1e\u0e32\u0e30\u0e23\u0e30\u0e1a\u0e1a\u0e21\u0e31\u0e25\u0e15\u0e34\u0e21\u0e35\u0e40\u0e14\u0e35\u0e22 MBUX7 \u0e40\u0e08\u0e40\u0e19\u0e2d\u0e40\u0e23\u0e0a\u0e31\u0e19\u0e43\u0e2b\u0e21\u0e48 \u0e41\u0e25\u0e30\u0e23\u0e30\u0e1a\u0e1a\u0e04\u0e27\u0e32\u0e21\u0e1b\u0e25\u0e2d\u0e14\u0e20\u0e31\u0e22\u0e2a\u0e38\u0e14\u0e25\u0e49\u0e33\u0e2b\u0e19\u0e49\u0e32 \u0e17\u0e35\u0e48\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e22\u0e01\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e1b\u0e23\u0e30\u0e2a\u0e1a\u0e01\u0e32\u0e23\u0e13\u0e4c\u0e01\u0e32\u0e23\u0e02\u0e31\u0e1a\u0e02\u0e35\u0e48\u0e02\u0e36\u0e49\u0e19\u0e2d\u0e35\u0e01\u0e02\u0e31\u0e49\u0e19\u0e43\u0e19\u0e17\u0e38\u0e01\u0e23\u0e32\u0e22\u0e25\u0e30\u0e40\u0e2d\u0e35\u0e22\u0e14<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u0e21\u0e23. \u0e1a\u0e35\u0e40\u0e22\u0e34\u0e23\u0e4c\u0e19 \u0e01\u0e38\u0e0b\u0e40\u0e17\u0e23\u0e32 (\u0e17\u0e35\u0e48 2 \u0e08\u0e32\u0e01\u0e0b\u0e49\u0e32\u0e22) \u0e23\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e18\u0e32\u0e19\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e1d\u0e48\u0e32\u0e22\u0e02\u0e32\u0e22\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14 \u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17 \u0e40\u0e21\u0e2d\u0e23\u0e4c\u0e40\u0e0b\u0e40\u0e14\u0e2a-\u0e40\u0e1a\u0e19\u0e0b\u0e4c (\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22) \u0e08\u0e33\u0e01\u0e31\u0e14 \u0e2a\u0e48\u0e07\u0e21\u0e2d\u0e1a\u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c \u201cMercedes-Benz S 350 d Exclusive\u201d \u0e08\u0e33\u0e19\u0e27\u0e19 6 \u0e04\u0e31\u0e19<\/p>\n","protected":false},"author":3,"featured_media":100054,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","footnotes":""},"categories":[3],"tags":[355],"class_list":["post-100053","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-car","tag-355"],"_links":{"self":[{"href":"https:\/\/www.benewsonline.com\/home\/wp-json\/wp\/v2\/posts\/100053","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.benewsonline.com\/home\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.benewsonline.com\/home\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.benewsonline.com\/home\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.benewsonline.com\/home\/wp-json\/wp\/v2\/comments?post=100053"}],"version-history":[{"count":1,"href":"https:\/\/www.benewsonline.com\/home\/wp-json\/wp\/v2\/posts\/100053\/revisions"}],"predecessor-version":[{"id":100055,"href":"https:\/\/www.benewsonline.com\/home\/wp-json\/wp\/v2\/posts\/100053\/revisions\/100055"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.benewsonline.com\/home\/wp-json\/wp\/v2\/media\/100054"}],"wp:attachment":[{"href":"https:\/\/www.benewsonline.com\/home\/wp-json\/wp\/v2\/media?parent=100053"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.benewsonline.com\/home\/wp-json\/wp\/v2\/categories?post=100053"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.benewsonline.com\/home\/wp-json\/wp\/v2\/tags?post=100053"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}