{"id":45878,"date":"2018-09-15T10:42:22","date_gmt":"2018-09-15T03:42:22","guid":{"rendered":"http:\/\/www.benewsonline.com\/wp-content\/uploads\/2018\/09\/3.\u0e2d\u0e07\u0e04\u0e4c\u0e01\u0e23\u0e15\u0e48\u0e32\u0e07\u0e46\u0e40\u0e02\u0e49\u0e32\u0e23\u0e48\u0e27\u0e21\u0e07\u0e32\u0e19.jpg"},"modified":"2018-09-15T10:42:22","modified_gmt":"2018-09-15T03:42:22","slug":"3-%e0%b8%ad%e0%b8%87%e0%b8%84%e0%b9%8c%e0%b8%81%e0%b8%a3%e0%b8%95%e0%b9%88%e0%b8%b2%e0%b8%87%e0%b9%86%e0%b9%80%e0%b8%82%e0%b9%89%e0%b8%b2%e0%b8%a3%e0%b9%88%e0%b8%a7%e0%b8%a1%e0%b8%87%e0%b8%b2%e0%b8%99","status":"inherit","type":"attachment","link":"https:\/\/www.benewsonline.com\/home\/2018\/09\/thailand-village-tourism-trade-meet-2018-%e0%b9%80%e0%b8%9b%e0%b8%b4%e0%b8%94%e0%b8%95%e0%b8%b1%e0%b8%a7-54-%e0%b8%8a%e0%b8%b8%e0%b8%a1%e0%b8%8a%e0%b8%99%e0%b8%97%e0%b9%88%e0%b8%ad%e0%b8%87%e0%b9%80\/3-%e0%b8%ad%e0%b8%87%e0%b8%84%e0%b9%8c%e0%b8%81%e0%b8%a3%e0%b8%95%e0%b9%88%e0%b8%b2%e0%b8%87%e0%b9%86%e0%b9%80%e0%b8%82%e0%b9%89%e0%b8%b2%e0%b8%a3%e0%b9%88%e0%b8%a7%e0%b8%a1%e0%b8%87%e0%b8%b2%e0%b8%99\/","title":{"rendered":"3.\u0e2d\u0e07\u0e04\u0e4c\u0e01\u0e23\u0e15\u0e48\u0e32\u0e07\u0e46\u0e40\u0e02\u0e49\u0e32\u0e23\u0e48\u0e27\u0e21\u0e07\u0e32\u0e19"},"author":3,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout"},"class_list":["post-45878","attachment","type-attachment","status-inherit","hentry"],"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/www.benewsonline.com\/wp-content\/uploads\/2018\/09\/3.\u0e2d\u0e07\u0e04\u0e4c\u0e01\u0e23\u0e15\u0e48\u0e32\u0e07\u0e46\u0e40\u0e02\u0e49\u0e32\u0e23\u0e48\u0e27\u0e21\u0e07\u0e32\u0e19.jpg'><img fetchpriority=\"high\" decoding=\"async\" width=\"300\" height=\"200\" src=\"https:\/\/www.benewsonline.com\/wp-content\/uploads\/2018\/09\/3.\u0e2d\u0e07\u0e04\u0e4c\u0e01\u0e23\u0e15\u0e48\u0e32\u0e07\u0e46\u0e40\u0e02\u0e49\u0e32\u0e23\u0e48\u0e27\u0e21\u0e07\u0e32\u0e19-300x200.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.benewsonline.com\/wp-content\/uploads\/2018\/09\/3.\u0e2d\u0e07\u0e04\u0e4c\u0e01\u0e23\u0e15\u0e48\u0e32\u0e07\u0e46\u0e40\u0e02\u0e49\u0e32\u0e23\u0e48\u0e27\u0e21\u0e07\u0e32\u0e19-300x200.jpg 300w, https:\/\/www.benewsonline.com\/wp-content\/uploads\/2018\/09\/3.\u0e2d\u0e07\u0e04\u0e4c\u0e01\u0e23\u0e15\u0e48\u0e32\u0e07\u0e46\u0e40\u0e02\u0e49\u0e32\u0e23\u0e48\u0e27\u0e21\u0e07\u0e32\u0e19-768x512.jpg 768w, https:\/\/www.benewsonline.com\/wp-content\/uploads\/2018\/09\/3.\u0e2d\u0e07\u0e04\u0e4c\u0e01\u0e23\u0e15\u0e48\u0e32\u0e07\u0e46\u0e40\u0e02\u0e49\u0e32\u0e23\u0e48\u0e27\u0e21\u0e07\u0e32\u0e19.jpg 800w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":800,"height":533,"file":"2018\/09\/3.\u0e2d\u0e07\u0e04\u0e4c\u0e01\u0e23\u0e15\u0e48\u0e32\u0e07\u0e46\u0e40\u0e02\u0e49\u0e32\u0e23\u0e48\u0e27\u0e21\u0e07\u0e32\u0e19.jpg","sizes":{"thumbnail":{"file":"3.\u0e2d\u0e07\u0e04\u0e4c\u0e01\u0e23\u0e15\u0e48\u0e32\u0e07\u0e46\u0e40\u0e02\u0e49\u0e32\u0e23\u0e48\u0e27\u0e21\u0e07\u0e32\u0e19-150x150.jpg","width":150,"height":150,"mime_type":"image\/jpeg","source_url":"https:\/\/www.benewsonline.com\/wp-content\/uploads\/2018\/09\/3.\u0e2d\u0e07\u0e04\u0e4c\u0e01\u0e23\u0e15\u0e48\u0e32\u0e07\u0e46\u0e40\u0e02\u0e49\u0e32\u0e23\u0e48\u0e27\u0e21\u0e07\u0e32\u0e19-150x150.jpg"},"medium":{"file":"3.\u0e2d\u0e07\u0e04\u0e4c\u0e01\u0e23\u0e15\u0e48\u0e32\u0e07\u0e46\u0e40\u0e02\u0e49\u0e32\u0e23\u0e48\u0e27\u0e21\u0e07\u0e32\u0e19-300x200.jpg","width":300,"height":200,"mime_type":"image\/jpeg","source_url":"https:\/\/www.benewsonline.com\/wp-content\/uploads\/2018\/09\/3.\u0e2d\u0e07\u0e04\u0e4c\u0e01\u0e23\u0e15\u0e48\u0e32\u0e07\u0e46\u0e40\u0e02\u0e49\u0e32\u0e23\u0e48\u0e27\u0e21\u0e07\u0e32\u0e19-300x200.jpg"},"medium_large":{"file":"3.\u0e2d\u0e07\u0e04\u0e4c\u0e01\u0e23\u0e15\u0e48\u0e32\u0e07\u0e46\u0e40\u0e02\u0e49\u0e32\u0e23\u0e48\u0e27\u0e21\u0e07\u0e32\u0e19-768x512.jpg","width":768,"height":512,"mime_type":"image\/jpeg","source_url":"https:\/\/www.benewsonline.com\/wp-content\/uploads\/2018\/09\/3.\u0e2d\u0e07\u0e04\u0e4c\u0e01\u0e23\u0e15\u0e48\u0e32\u0e07\u0e46\u0e40\u0e02\u0e49\u0e32\u0e23\u0e48\u0e27\u0e21\u0e07\u0e32\u0e19-768x512.jpg"},"colormag-highlighted-post":{"file":"3.\u0e2d\u0e07\u0e04\u0e4c\u0e01\u0e23\u0e15\u0e48\u0e32\u0e07\u0e46\u0e40\u0e02\u0e49\u0e32\u0e23\u0e48\u0e27\u0e21\u0e07\u0e32\u0e19-392x272.jpg","width":392,"height":272,"mime_type":"image\/jpeg","source_url":"https:\/\/www.benewsonline.com\/wp-content\/uploads\/2018\/09\/3.\u0e2d\u0e07\u0e04\u0e4c\u0e01\u0e23\u0e15\u0e48\u0e32\u0e07\u0e46\u0e40\u0e02\u0e49\u0e32\u0e23\u0e48\u0e27\u0e21\u0e07\u0e32\u0e19-392x272.jpg"},"colormag-featured-post-medium":{"file":"3.\u0e2d\u0e07\u0e04\u0e4c\u0e01\u0e23\u0e15\u0e48\u0e32\u0e07\u0e46\u0e40\u0e02\u0e49\u0e32\u0e23\u0e48\u0e27\u0e21\u0e07\u0e32\u0e19-390x205.jpg","width":390,"height":205,"mime_type":"image\/jpeg","source_url":"https:\/\/www.benewsonline.com\/wp-content\/uploads\/2018\/09\/3.\u0e2d\u0e07\u0e04\u0e4c\u0e01\u0e23\u0e15\u0e48\u0e32\u0e07\u0e46\u0e40\u0e02\u0e49\u0e32\u0e23\u0e48\u0e27\u0e21\u0e07\u0e32\u0e19-390x205.jpg"},"colormag-featured-post-small":{"file":"3.\u0e2d\u0e07\u0e04\u0e4c\u0e01\u0e23\u0e15\u0e48\u0e32\u0e07\u0e46\u0e40\u0e02\u0e49\u0e32\u0e23\u0e48\u0e27\u0e21\u0e07\u0e32\u0e19-130x90.jpg","width":130,"height":90,"mime_type":"image\/jpeg","source_url":"https:\/\/www.benewsonline.com\/wp-content\/uploads\/2018\/09\/3.\u0e2d\u0e07\u0e04\u0e4c\u0e01\u0e23\u0e15\u0e48\u0e32\u0e07\u0e46\u0e40\u0e02\u0e49\u0e32\u0e23\u0e48\u0e27\u0e21\u0e07\u0e32\u0e19-130x90.jpg"},"colormag-featured-image":{"file":"3.\u0e2d\u0e07\u0e04\u0e4c\u0e01\u0e23\u0e15\u0e48\u0e32\u0e07\u0e46\u0e40\u0e02\u0e49\u0e32\u0e23\u0e48\u0e27\u0e21\u0e07\u0e32\u0e19-800x445.jpg","width":800,"height":445,"mime_type":"image\/jpeg","source_url":"https:\/\/www.benewsonline.com\/wp-content\/uploads\/2018\/09\/3.\u0e2d\u0e07\u0e04\u0e4c\u0e01\u0e23\u0e15\u0e48\u0e32\u0e07\u0e46\u0e40\u0e02\u0e49\u0e32\u0e23\u0e48\u0e27\u0e21\u0e07\u0e32\u0e19-800x445.jpg"},"full":{"file":"3.\u0e2d\u0e07\u0e04\u0e4c\u0e01\u0e23\u0e15\u0e48\u0e32\u0e07\u0e46\u0e40\u0e02\u0e49\u0e32\u0e23\u0e48\u0e27\u0e21\u0e07\u0e32\u0e19.jpg","width":800,"height":533,"mime_type":"image\/jpeg","source_url":"https:\/\/www.benewsonline.com\/wp-content\/uploads\/2018\/09\/3.\u0e2d\u0e07\u0e04\u0e4c\u0e01\u0e23\u0e15\u0e48\u0e32\u0e07\u0e46\u0e40\u0e02\u0e49\u0e32\u0e23\u0e48\u0e27\u0e21\u0e07\u0e32\u0e19.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"1536912756","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":45877,"source_url":"https:\/\/www.benewsonline.com\/wp-content\/uploads\/2018\/09\/3.\u0e2d\u0e07\u0e04\u0e4c\u0e01\u0e23\u0e15\u0e48\u0e32\u0e07\u0e46\u0e40\u0e02\u0e49\u0e32\u0e23\u0e48\u0e27\u0e21\u0e07\u0e32\u0e19.jpg","_links":{"self":[{"href":"https:\/\/www.benewsonline.com\/home\/wp-json\/wp\/v2\/media\/45878","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.benewsonline.com\/home\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/www.benewsonline.com\/home\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/www.benewsonline.com\/home\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.benewsonline.com\/home\/wp-json\/wp\/v2\/comments?post=45878"}],"wp:attached-to":[{"embeddable":true,"post_type":"post","id":45877,"href":"https:\/\/www.benewsonline.com\/home\/wp-json\/wp\/v2\/posts\/45877"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}